{"id":1213,"date":"2017-07-18T14:51:12","date_gmt":"2017-07-18T14:51:12","guid":{"rendered":"http:\/\/ciutadella.salesians.cat\/escola\/?page_id=1213"},"modified":"2025-09-20T14:32:28","modified_gmt":"2025-09-20T14:32:28","slug":"salutaciodeldirector","status":"publish","type":"page","link":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/","title":{"rendered":"Salutaci\u00f3"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb next_background_color=\u00bb#000000&#8243;][et_pb_fullwidth_header title=\u00bbSalutaci\u00f3 del director\u00bb content_max_width=\u00bbnone\u00bb title_font_color=\u00bb#ffffff\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.26.0&#8243; title_text_color=\u00bb#ffffff\u00bb title_font_size=\u00bb40px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2017\/07\/fbk.png\u00bb vertical_offset_tablet=\u00bb0&#8243; horizontal_offset_tablet=\u00bb0&#8243; background_layout=\u00bblight\u00bb z_index_tablet=\u00bb0&#8243; title_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb title_text_shadow_vertical_length_tablet=\u00bb0px\u00bb title_text_shadow_blur_strength_tablet=\u00bb1px\u00bb content_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb content_text_shadow_vertical_length_tablet=\u00bb0px\u00bb content_text_shadow_blur_strength_tablet=\u00bb1px\u00bb subhead_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb subhead_text_shadow_vertical_length_tablet=\u00bb0px\u00bb subhead_text_shadow_blur_strength_tablet=\u00bb1px\u00bb content_link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb content_link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb content_link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb content_ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb content_ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb content_ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb content_ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb content_ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb content_ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb content_quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb content_quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb content_quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb button_one_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb button_one_text_shadow_vertical_length_tablet=\u00bb0px\u00bb button_one_text_shadow_blur_strength_tablet=\u00bb1px\u00bb button_two_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb button_two_text_shadow_vertical_length_tablet=\u00bb0px\u00bb button_two_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb box_shadow_horizontal_image_tablet=\u00bb0px\u00bb box_shadow_vertical_image_tablet=\u00bb0px\u00bb box_shadow_blur_image_tablet=\u00bb40px\u00bb box_shadow_spread_image_tablet=\u00bb0px\u00bb box_shadow_horizontal_button_one_tablet=\u00bb0px\u00bb box_shadow_vertical_button_one_tablet=\u00bb0px\u00bb box_shadow_blur_button_one_tablet=\u00bb40px\u00bb box_shadow_spread_button_one_tablet=\u00bb0px\u00bb box_shadow_horizontal_button_two_tablet=\u00bb0px\u00bb box_shadow_vertical_button_two_tablet=\u00bb0px\u00bb box_shadow_blur_button_two_tablet=\u00bb40px\u00bb box_shadow_spread_button_two_tablet=\u00bb0px\u00bb text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_shadow_blur_strength_tablet=\u00bb1px\u00bb background_url=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2017\/02\/IMG_3144.jpg\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; button_two_letter_spacing_hover=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover=\u00bbnull\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover=\u00bbnull\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover=\u00bbnull\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover=\u00bbnull\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover=\u00bbnull\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover=\u00bbnull\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover=\u00bbnull\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover=\u00bbnull\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover=\u00bbnull\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover=\u00bbnull\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb0&#8243; button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb0&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover=\u00bbnull\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover=\u00bbnull\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section bb_built=\u00bb1&#8243; module_class=\u00bbpagina-seccion-contenido\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb-4%|||\u00bb transparent_background=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb prev_background_color=\u00bb#000000&#8243; next_background_color=\u00bb#000000&#8243;][et_pb_row module_class=\u00bbpagina-texto\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; vertical_offset_tablet=\u00bb0&#8243; horizontal_offset_tablet=\u00bb0&#8243; z_index_tablet=\u00bb0&#8243; text_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_text_shadow_blur_strength_tablet=\u00bb1px\u00bb link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_2_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_2_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_2_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_3_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_3_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_3_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_4_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_4_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_4_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_5_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_5_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_5_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_6_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_6_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_6_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Salutaci\u00f3 del director<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font_size=\u00bb15px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb vertical_offset_tablet=\u00bb0&#8243; horizontal_offset_tablet=\u00bb0&#8243; z_index_tablet=\u00bb500&#8243; text_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_text_shadow_blur_strength_tablet=\u00bb1px\u00bb link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_2_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_2_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_2_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_3_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_3_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_3_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_4_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_4_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_4_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_5_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_5_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_5_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_6_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_6_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_6_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb background_pattern_color=\u00bbrgba(0,0,0,0.2)\u00bb background_mask_color=\u00bb#ffffff\u00bb text_text_shadow_horizontal_length=\u00bbtext_text_shadow_style,%91object Object%93&#8243; text_text_shadow_vertical_length=\u00bbtext_text_shadow_style,%91object Object%93&#8243; text_text_shadow_blur_strength=\u00bbtext_text_shadow_style,%91object Object%93&#8243; link_text_shadow_horizontal_length=\u00bblink_text_shadow_style,%91object Object%93&#8243; link_text_shadow_vertical_length=\u00bblink_text_shadow_style,%91object Object%93&#8243; link_text_shadow_blur_strength=\u00bblink_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_horizontal_length=\u00bbul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_vertical_length=\u00bbul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_blur_strength=\u00bbul_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_horizontal_length=\u00bbol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_vertical_length=\u00bbol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_blur_strength=\u00bbol_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_horizontal_length=\u00bbquote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_vertical_length=\u00bbquote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_blur_strength=\u00bbquote_text_shadow_style,%91object Object%93&#8243; header_text_shadow_horizontal_length=\u00bbheader_text_shadow_style,%91object Object%93&#8243; header_text_shadow_vertical_length=\u00bbheader_text_shadow_style,%91object Object%93&#8243; header_text_shadow_blur_strength=\u00bbheader_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_horizontal_length=\u00bbheader_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_vertical_length=\u00bbheader_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_blur_strength=\u00bbheader_2_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_horizontal_length=\u00bbheader_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_vertical_length=\u00bbheader_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_blur_strength=\u00bbheader_3_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_horizontal_length=\u00bbheader_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_vertical_length=\u00bbheader_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_blur_strength=\u00bbheader_4_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_horizontal_length=\u00bbheader_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_vertical_length=\u00bbheader_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_blur_strength=\u00bbheader_5_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_horizontal_length=\u00bbheader_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_vertical_length=\u00bbheader_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_blur_strength=\u00bbheader_6_text_shadow_style,%91object Object%93&#8243;]<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-6716\" src=\"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-1024x768.jpg\" alt=\"\" width=\"376\" height=\"282\" \/><span style=\"font-size: 15px;\">Benvolguts i benvolgudes,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A l\u2019escola de Cal\u00f3s vivim cada curs com una nova oportunitat per continuar construint una hist\u00f2ria compartida. No es tracta nom\u00e9s de formar persones preparades acad\u00e8micament, sin\u00f3 d\u2019acompanyar camins vitals plens de sentit, amb el des<\/span><span style=\"font-weight: 400;\">ig que cadasc\u00fa arribi a ser el millor de si mateix\/a amb un model de persona ben definit.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El lema d\u2019aquest curs \u2014\u201cProtagonistes de la hist\u00f2ria\u201d\u2014 ens convida a recon\u00e8ixer que cadascun de nosaltres forma part d\u2019una gran hist\u00f2ria d\u2019amor i de vida. No som simples espectadors\/es del nostre temps, sin\u00f3 protagonistes cridats a viure amb sentit i a compartir la vida amb els altres amb responsabilitat.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Aquest curs ens anima a redescobrir la nostra pr\u00f2pia vocaci\u00f3 enmig de la comunitat, a viure amb autenticitat i a regalar tot all\u00f2 que som. Ho farem des de la senzillesa i des del comprom\u00eds amb els valors que Sant Joan Bosco ens va transmetre: acollida, alegria, servei i esperan\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Us convid, id\u00f2, a continuar formant part d\u2019aquest projecte educatiu i pastoral o a sumar-vos-hi si us hi voleu sentir tamb\u00e9 protagonistes. Una proposta que nom\u00e9s \u00e9s possible amb la implicaci\u00f3 de l\u2019alumnat, les fam\u00edlies, els educadors\/es, el personal no docent i la comunitat salesiana. De la m\u00e0 de tothom, seguirem escrivint la nostra hist\u00f2ria: una hist\u00f2ria de futur i d\u2019esperan\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Gr\u00e0cies per la vostra confian\u00e7a i benvinguts a casa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cordialment,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Guillem Benejam Taltavull\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">Director<\/span><\/i><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb3px|0px|0px|0px\u00bb transparent_background=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bboff\u00bb custom_width_px=\u00bb1080px\u00bb custom_width_percent=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb prev_background_color=\u00bb#000000&#8243;][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bboff\u00bb custom_width_px=\u00bb1080px\u00bb custom_width_percent=\u00bb80%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb admin_label=\u00bbActualidad\u00bb title=\u00bbEscola\u00bb url=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/opcionspreferencials\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe009;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb48px\u00bb _builder_version=\u00bb4.16&#8243; header_text_color=\u00bb#66757e\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bb#66757e\u00bb border_style=\u00bbsolid\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bb#66757e\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb admin_label=\u00bbActualidad\u00bb title=\u00bbOpcions preferencials\u00bb url=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/1034-2\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe00a;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb48px\u00bb _builder_version=\u00bb4.16&#8243; header_text_color=\u00bb#66757e\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bb#66757e\u00bb border_style=\u00bbsolid\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bb#66757e\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb admin_label=\u00bbActualidad\u00bb title=\u00bbOrganigrama\u00bb url=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/organigrama\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe109;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb48px\u00bb _builder_version=\u00bb4.16&#8243; header_text_color=\u00bb#66757e\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bb#66757e\u00bb border_style=\u00bbsolid\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bb#66757e\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb admin_label=\u00bbActualidad\u00bb title=\u00bbPol\u00edtica de qualitat\u00bb url=\u00bbhttp:\/\/ciutadella.salesians.cat\/escola\/politica-de-qualitat\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe0e9;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb48px\u00bb _builder_version=\u00bb4.16&#8243; header_text_color=\u00bb#66757e\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bb#66757e\u00bb border_style=\u00bbsolid\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bb#66757e\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salutaci\u00f3 del director \u00a0\u00a0Benvolguts i benvolgudes,A l\u2019escola de Cal\u00f3s vivim cada curs com una nova oportunitat per continuar construint una hist\u00f2ria compartida. No es tracta nom\u00e9s de formar persones preparades acad\u00e8micament, sin\u00f3 d\u2019acompanyar camins vitals plens de sentit, amb el desig que cadasc\u00fa arribi a ser el millor de si mateix\/a amb un model de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1213","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salutaci\u00f3 - Escola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salutaci\u00f3 - Escola\" \/>\n<meta property=\"og:description\" content=\"Salutaci\u00f3 del director \u00a0\u00a0Benvolguts i benvolgudes,A l\u2019escola de Cal\u00f3s vivim cada curs com una nova oportunitat per continuar construint una hist\u00f2ria compartida. No es tracta nom\u00e9s de formar persones preparades acad\u00e8micament, sin\u00f3 d\u2019acompanyar camins vitals plens de sentit, amb el desig que cadasc\u00fa arribi a ser el millor de si mateix\/a amb un model de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/\" \/>\n<meta property=\"og:site_name\" content=\"Escola\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-20T14:32:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/\",\"url\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/\",\"name\":\"Salutaci\u00f3 - Escola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_7609-1024x768.jpg\",\"datePublished\":\"2017-07-18T14:51:12+00:00\",\"dateModified\":\"2025-09-20T14:32:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_7609-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_7609-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/salutaciodeldirector\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salutaci\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/#website\",\"url\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/\",\"name\":\"Escola\",\"description\":\"P\u00e0gina oficial de Salesians Ciutadella\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ciutadella.salesians.cat\\\/escola\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salutaci\u00f3 - Escola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/","og_locale":"es_ES","og_type":"article","og_title":"Salutaci\u00f3 - Escola","og_description":"Salutaci\u00f3 del director \u00a0\u00a0Benvolguts i benvolgudes,A l\u2019escola de Cal\u00f3s vivim cada curs com una nova oportunitat per continuar construint una hist\u00f2ria compartida. No es tracta nom\u00e9s de formar persones preparades acad\u00e8micament, sin\u00f3 d\u2019acompanyar camins vitals plens de sentit, amb el desig que cadasc\u00fa arribi a ser el millor de si mateix\/a amb un model de [&hellip;]","og_url":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/","og_site_name":"Escola","article_modified_time":"2025-09-20T14:32:28+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/","url":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/","name":"Salutaci\u00f3 - Escola","isPartOf":{"@id":"https:\/\/ciutadella.salesians.cat\/escola\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/#primaryimage"},"image":{"@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/#primaryimage"},"thumbnailUrl":"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-1024x768.jpg","datePublished":"2017-07-18T14:51:12+00:00","dateModified":"2025-09-20T14:32:28+00:00","breadcrumb":{"@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/#primaryimage","url":"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-scaled.jpg","contentUrl":"https:\/\/ciutadella.salesians.cat\/escola\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_7609-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/ciutadella.salesians.cat\/escola\/salutaciodeldirector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ciutadella.salesians.cat\/escola\/"},{"@type":"ListItem","position":2,"name":"Salutaci\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/ciutadella.salesians.cat\/escola\/#website","url":"https:\/\/ciutadella.salesians.cat\/escola\/","name":"Escola","description":"P\u00e0gina oficial de Salesians Ciutadella","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciutadella.salesians.cat\/escola\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/pages\/1213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/comments?post=1213"}],"version-history":[{"count":37,"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/pages\/1213\/revisions"}],"predecessor-version":[{"id":6718,"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/pages\/1213\/revisions\/6718"}],"wp:attachment":[{"href":"https:\/\/ciutadella.salesians.cat\/escola\/wp-json\/wp\/v2\/media?parent=1213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}